{"id":164464,"date":"2026-05-13T03:21:13","date_gmt":"2026-05-13T01:21:13","guid":{"rendered":"https:\/\/webshop.schuetz-dental.org\/product\/t98-schaftfraeser-25-mm-zum-kalibrieren-dreischneider-tizian-cut-5-tizian-1-5-2-5-fuer-3mm-spannzange\/"},"modified":"2026-05-13T03:21:15","modified_gmt":"2026-05-13T01:21:15","slug":"t98-schaftfraeser-25-mm-zum-kalibrieren-dreischneider-tizian-cut-5-tizian-1-5-2-5-fuer-3mm-spannzange","status":"publish","type":"product","link":"https:\/\/schuetz-dental.de\/en\/produkt\/t98-schaftfraeser-25-mm-zum-kalibrieren-dreischneider-tizian-cut-5-tizian-1-5-2-5-fuer-3mm-spannzange\/","title":{"rendered":"T98 Schaftfr\u00e4ser 2,5 mm zum kalibrieren, Dreischneider, Tizian Cut 5\/ Tizian 1.5\/ 2.5 f\u00fcr 3mm Spannzange"},"content":{"rendered":"<p><strong>T98 &#8211; Schaftfr\u00e4ser\u00a0zur Kalibrierung Ihres Tizian Fr\u00e4ssystems<\/strong><\/p>\n<ul>\n<li><strong>Durchmesser\u00a0<\/strong>\u00d8 2,5 mm<\/li>\n<li><strong>Schneiden<\/strong>\u00a0dreischneidig<\/li>\n<li><strong>Schaft<\/strong>\u00a0\u00d8 3 mm<\/li>\n<li><strong>Freistell-L\u00e4nge:<\/strong>\u00a0l = 20 mm<\/li>\n<li><strong>Gesamtl\u00e4nge:<\/strong>\u00a045 mm<\/li>\n<li><strong>Beschichtungsart:<\/strong>\u00a0unbeschichtet<\/li>\n<li><strong>F\u00fcr Fr\u00e4smaschinen:<\/strong> Tizian 1.5 Pro, Tizian 2.5 Loader Pro, Tizian Cut 5<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Schaftfr\u00e4ser f\u00fcr Ihr Tizian Fr\u00e4ssystem.<\/p>\n","protected":false},"featured_media":449924,"template":"","meta":{"_acf_changed":false,"_price":"46.8","_stock":"0.000000","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tec_slr_enabled":"","_tec_slr_layout":""},"product_brand":[],"product_cat":[4540,4547],"product_tag":[],"class_list":{"0":"post-164464","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-3-mm-spannzange","7":"product_cat-tizian-1-5-tizian-2-5","9":"first","10":"instock","11":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/schuetz-dental.de\/en\/wp-json\/wp\/v2\/product\/164464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schuetz-dental.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/schuetz-dental.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schuetz-dental.de\/en\/wp-json\/wp\/v2\/media\/449924"}],"wp:attachment":[{"href":"https:\/\/schuetz-dental.de\/en\/wp-json\/wp\/v2\/media?parent=164464"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/schuetz-dental.de\/en\/wp-json\/wp\/v2\/product_brand?post=164464"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/schuetz-dental.de\/en\/wp-json\/wp\/v2\/product_cat?post=164464"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/schuetz-dental.de\/en\/wp-json\/wp\/v2\/product_tag?post=164464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}